{"id":2132,"date":"2026-04-02T14:35:05","date_gmt":"2026-04-02T11:35:05","guid":{"rendered":"https:\/\/dryunusoc.com\/hospital\/"},"modified":"2026-04-24T15:40:07","modified_gmt":"2026-04-24T12:40:07","slug":"notre-hopital","status":"publish","type":"page","link":"https:\/\/dryunusoc.com\/fr\/notre-hopital\/","title":{"rendered":"Notre h\u00f4pital"},"content":{"rendered":"\n<section class=\"section hp-section section-bg-white\">\n    <div class=\"container\">\n\n                <div class=\"hp-header animate-on-scroll\">\n                                                <p class=\"hp-intro\">Notre h\u00f4pital compte parmi les centres de sant\u00e9 de r\u00e9f\u00e9rence en Turquie, gr\u00e2ce \u00e0 son architecture moderne, son hall spacieux et ses infrastructures de pointe. Il a \u00e9t\u00e9 con\u00e7u pour offrir un environnement s\u00fbr, confortable et de haute qualit\u00e9 pour les interventions d\u2019allongement des membres. Pendant les phases chirurgicale et de r\u00e9cup\u00e9ration, notre objectif est de garantir une exp\u00e9rience fiable, centr\u00e9e sur le patient et conforme aux normes de soins les plus \u00e9lev\u00e9es.<\/p>        <\/div>\n        \n        \n                        <div class=\"hp-block hp-image-video animate-on-scroll\">\n                                <div class=\"hp-iv-image\">\n                    <img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/bht-clinic-hospital.jpg\" alt=\"\" loading=\"lazy\">\n                <\/div>\n                                                <div class=\"hp-iv-video\">\n                    <iframe src=\"https:\/\/www.youtube.com\/embed\/inDkEx-HqlI?rel=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen loading=\"lazy\"><\/iframe>\n                <\/div>\n                            <\/div>\n\n            \n        \n                        <div class=\"hp-block hp-feature animate-on-scroll\">\n                <div class=\"hp-feature-text\">\n                    <h3 class=\"hp-feature-title\">Un accueil spacieux et moderne : grand hall<\/h3>                    <div class=\"hp-feature-content\"><p data-start=\"33\" data-end=\"280\">D\u00e8s votre entr\u00e9e dans notre h\u00f4pital, vous \u00eates accueilli par un hall spacieux et soigneusement con\u00e7u, qui refl\u00e8te une atmosph\u00e8re moderne et \u00e9l\u00e9gante. D\u00e8s le premier instant, tout est pens\u00e9 pour que vous vous sentiez \u00e0 l\u2019aise, en s\u00e9curit\u00e9 et bien pris en charge.<\/p>\n<p data-start=\"282\" data-end=\"528\">Le hall n\u2019a pas \u00e9t\u00e9 con\u00e7u uniquement pour son esth\u00e9tique, mais aussi pour sa fonctionnalit\u00e9. Avec ses larges espaces assis, sa lumi\u00e8re naturelle et son ambiance apaisante, il offre un lieu serein o\u00f9 les patients et leurs accompagnants peuvent se d\u00e9tendre avant ou apr\u00e8s les proc\u00e9dures m\u00e9dicales.<\/p>\n<p data-start=\"530\" data-end=\"769\">Chaque d\u00e9tail a \u00e9t\u00e9 soigneusement pens\u00e9 pour am\u00e9liorer votre exp\u00e9rience globale. Que vous attendiez votre rendez-vous ou que vous souhaitiez simplement vous reposer un moment, cet espace vous offre un environnement accueillant et sans stress tout au long de votre s\u00e9jour.<\/p>\n<\/div>                <\/div>\n                                <div class=\"hp-feature-media\">\n                    <img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/bht-clinic-hospital-2.jpg\" alt=\"Un accueil spacieux et moderne : grand hall\" loading=\"lazy\">\n                <\/div>\n                            <\/div>\n\n            \n        \n                        <div class=\"hp-block hp-tech animate-on-scroll\">\n                <h3 class=\"hp-tech-title\">Infrastructure technologique avanc\u00e9e<\/h3>                <p class=\"hp-tech-desc\">Notre h\u00f4pital est \u00e9quip\u00e9 de toutes les technologies m\u00e9dicales n\u00e9cessaires \u00e0 la chirurgie d\u2019allongement des membres. Des syst\u00e8mes avanc\u00e9s de diagnostic et de d\u00e9pistage sont utilis\u00e9s afin de garantir une \u00e9valuation pr\u00e9cise, une planification s\u00fbre et un traitement de haute qualit\u00e9 tout au long du processus.\r\n\r\nDes techniques modernes et largement reconnues telles que Precice, LON et Fitbone sont appliqu\u00e9es lors des interventions chirurgicales, permettant aux patients de b\u00e9n\u00e9ficier des derni\u00e8res avanc\u00e9es en mati\u00e8re de m\u00e9thodes d\u2019allongement des membres.<\/p>                                <div class=\"hp-tech-list\">\n                                        <div class=\"hp-tech-chip\">\n                        <span class=\"hp-tech-chip-num\">01<\/span>\n                        <span class=\"hp-tech-chip-name\">IRM corps entier<\/span>\n                    <\/div>\n                                        <div class=\"hp-tech-chip\">\n                        <span class=\"hp-tech-chip-num\">02<\/span>\n                        <span class=\"hp-tech-chip-name\">\u00c9chographie<\/span>\n                    <\/div>\n                                        <div class=\"hp-tech-chip\">\n                        <span class=\"hp-tech-chip-num\">03<\/span>\n                        <span class=\"hp-tech-chip-name\">Angiographie num\u00e9rique DSA<\/span>\n                    <\/div>\n                                        <div class=\"hp-tech-chip\">\n                        <span class=\"hp-tech-chip-num\">04<\/span>\n                        <span class=\"hp-tech-chip-name\">PET-CT<\/span>\n                    <\/div>\n                                        <div class=\"hp-tech-chip\">\n                        <span class=\"hp-tech-chip-num\">05<\/span>\n                        <span class=\"hp-tech-chip-name\">TrueBeam<\/span>\n                    <\/div>\n                                        <div class=\"hp-tech-chip\">\n                        <span class=\"hp-tech-chip-num\">06<\/span>\n                        <span class=\"hp-tech-chip-name\">Trilogy<\/span>\n                    <\/div>\n                                        <div class=\"hp-tech-chip\">\n                        <span class=\"hp-tech-chip-num\">07<\/span>\n                        <span class=\"hp-tech-chip-name\">Radioth\u00e9rapie<\/span>\n                    <\/div>\n                                    <\/div>\n                                                <div class=\"hp-tech-gallery\" style=\"--hp-tech-cols: 4\">\n                                        <img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/bht-clinic-technology.jpg\" alt=\"\" loading=\"lazy\">\n                                        <img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/bht-clinic-technology-2.jpg\" alt=\"\" loading=\"lazy\">\n                                        <img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/bht-clinic-technology-3.jpg\" alt=\"\" loading=\"lazy\">\n                                        <img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/bht-clinic-technology-4.jpg\" alt=\"\" loading=\"lazy\">\n                                    <\/div>\n                                <p class=\"hp-tech-desc-bottom\">Nos dispositifs de diagnostic avanc\u00e9s et nos \u00e9quipements m\u00e9dicaux modernes permettent une \u00e9valuation pr\u00e9cise et une planification th\u00e9rapeutique efficace. Gr\u00e2ce \u00e0 ces technologies, les interventions chirurgicales sont r\u00e9alis\u00e9es avec un niveau sup\u00e9rieur de pr\u00e9cision, de s\u00e9curit\u00e9 et de fiabilit\u00e9.<\/p>            <\/div>\n\n            \n        \n                        <div class=\"hp-block hp-feature animate-on-scroll\">\n                <div class=\"hp-feature-text\">\n                    <h3 class=\"hp-feature-title\">\u00c9quipe m\u00e9dicale exp\u00e9riment\u00e9e<\/h3>                    <div class=\"hp-feature-content\"><p data-start=\"33\" data-end=\"334\">Nos chirurgiens, hautement exp\u00e9riment\u00e9s dans les proc\u00e9dures d\u2019allongement des membres, travaillent en \u00e9troite collaboration avec une \u00e9quipe qualifi\u00e9e d\u2019infirmiers et de sp\u00e9cialistes en physioth\u00e9rapie afin de garantir les normes de soins les plus \u00e9lev\u00e9es. Chaque membre de l\u2019\u00e9quipe joue un r\u00f4le essentiel pour accompagner le patient tout au long de son parcours de traitement.<\/p>\n<p data-start=\"336\" data-end=\"581\">Une approche multidisciplinaire est appliqu\u00e9e \u00e0 chaque \u00e9tape, depuis la planification pr\u00e9op\u00e9ratoire jusqu\u2019\u00e0 la r\u00e9\u00e9ducation postop\u00e9ratoire. Ce travail coordonn\u00e9 permet de proposer des plans de traitement personnalis\u00e9s, un suivi continu et des interventions rapides lorsque cela est n\u00e9cessaire.<\/p>\n<p data-start=\"583\" data-end=\"814\">En associant expertise chirurgicale, suivi postop\u00e9ratoire professionnel et soutien \u00e0 la r\u00e9\u00e9ducation, nous visons \u00e0 offrir aux patients une exp\u00e9rience s\u00fbre, bien structur\u00e9e et confortable, garantissant des r\u00e9sultats optimaux et une r\u00e9cup\u00e9ration plus fluide.<\/p>\n<\/div>                <\/div>\n                                <div class=\"hp-feature-media\">\n                    <img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/bht-clinic-team.jpg\" alt=\"\u00c9quipe m\u00e9dicale exp\u00e9riment\u00e9e\" loading=\"lazy\">\n                <\/div>\n                            <\/div>\n\n            \n        \n                        <div class=\"hp-block hp-feature hp-feature-reverse animate-on-scroll\">\n                <div class=\"hp-feature-text\">\n                    <h3 class=\"hp-feature-title\">Chambres des patients et espaces confortables<\/h3>                    <div class=\"hp-feature-content\"><p data-start=\"33\" data-end=\"297\">Les chambres de notre h\u00f4pital sont soigneusement con\u00e7ues pour offrir le plus haut niveau de confort pendant la p\u00e9riode de r\u00e9cup\u00e9ration postop\u00e9ratoire. Chaque d\u00e9tail est pens\u00e9 pour cr\u00e9er un environnement calme, s\u00fbr et rassurant, o\u00f9 les patients peuvent se reposer et se concentrer sur leur gu\u00e9rison.<\/p>\n<p data-start=\"299\" data-end=\"561\">Chaque chambre est \u00e9quip\u00e9e d\u2019installations m\u00e9dicales modernes et d\u2019\u00e9quipements de confort afin de r\u00e9pondre aux besoins des patients comme de leurs accompagnants. Les espaces g\u00e9n\u00e9reux, les lits hospitaliers r\u00e9glables et l\u2019acc\u00e8s facile aux \u00e9quipements essentiels garantissent praticit\u00e9 et fonctionnalit\u00e9 tout au long du s\u00e9jour.<\/p>\n<p data-start=\"563\" data-end=\"822\">En outre, les chambres sont entretenues selon des normes d\u2019hygi\u00e8ne \u00e9lev\u00e9es et offrent une atmosph\u00e8re paisible qui soutient \u00e0 la fois la r\u00e9cup\u00e9ration physique et mentale. Cet environnement confortable aide les patients \u00e0 se sentir en confiance tout en b\u00e9n\u00e9ficiant de soins continus et d\u2019une assistance lorsque n\u00e9cessaire.<\/p>\n<\/div>                <\/div>\n                                <div class=\"hp-feature-media\">\n                    <img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/bht-clinic-4-1-1.jpg\" alt=\"Chambres des patients et espaces confortables\" loading=\"lazy\">\n                <\/div>\n                            <\/div>\n\n            \n        \n                        <div class=\"hp-block hp-feature animate-on-scroll\">\n                <div class=\"hp-feature-text\">\n                    <h3 class=\"hp-feature-title\">Toilettes et salle de bain adapt\u00e9es<\/h3>                    <div class=\"hp-feature-content\"><p data-start=\"33\" data-end=\"270\">Toutes les chambres des patients comprennent une salle de bain et des toilettes privatives sp\u00e9cialement con\u00e7ues pour les personnes \u00e0 mobilit\u00e9 r\u00e9duite. Ces installations sont adapt\u00e9es afin d\u2019assurer facilit\u00e9 d\u2019utilisation, autonomie et confort maximal pendant la p\u00e9riode de r\u00e9cup\u00e9ration.<\/p>\n<p data-start=\"272\" data-end=\"495\">Leur conception privil\u00e9gie \u00e0 la fois l\u2019hygi\u00e8ne et la s\u00e9curit\u00e9, avec des am\u00e9nagements accessibles, des \u00e9quipements de soutien et des surfaces antid\u00e9rapantes. Chaque d\u00e9tail est soigneusement \u00e9tudi\u00e9 afin de r\u00e9duire les risques et d\u2019offrir un environnement s\u00fbr pour les besoins du quotidien.<\/p>\n<p data-start=\"497\" data-end=\"645\">Cette configuration pens\u00e9e avec soin permet aux patients de g\u00e9rer plus confortablement leur hygi\u00e8ne personnelle tout en maintenant un niveau \u00e9lev\u00e9 de propret\u00e9 pendant tout leur s\u00e9jour.<\/p>\n<\/div>                <\/div>\n                                <div class=\"hp-feature-media\">\n                    <img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/bht-clinic-bathroom.jpeg\" alt=\"Toilettes et salle de bain adapt\u00e9es\" loading=\"lazy\">\n                <\/div>\n                            <\/div>\n\n            \n        \n                        <div class=\"hp-block hp-feature hp-feature-reverse animate-on-scroll\">\n                <div class=\"hp-feature-text\">\n                    <h3 class=\"hp-feature-title\">Caf\u00e9<\/h3>                    <div class=\"hp-feature-content\"><p data-start=\"33\" data-end=\"295\">L\u2019espace caf\u00e9 moderne et spacieux de notre h\u00f4pital offre un lieu confortable o\u00f9 les patients et leurs accompagnants peuvent se d\u00e9tendre et faire une pause. Con\u00e7u dans une atmosph\u00e8re calme et accueillante, il propose un cadre agr\u00e9able pour se relaxer pendant le parcours de traitement.<\/p>\n<p data-start=\"297\" data-end=\"498\">Cet espace a \u00e9t\u00e9 soigneusement pens\u00e9 en tenant compte \u00e0 la fois de l\u2019hygi\u00e8ne et du confort. Des zones assises propres et bien organis\u00e9es, ainsi qu\u2019une ambiance apaisante, contribuent \u00e0 cr\u00e9er un espace s\u00fbr et agr\u00e9able pour les visiteurs tout au long de la journ\u00e9e.<\/p>\n<p data-start=\"500\" data-end=\"747\">En outre, le caf\u00e9 propose une vari\u00e9t\u00e9 d\u2019aliments et de boissons afin de r\u00e9pondre \u00e0 diff\u00e9rentes pr\u00e9f\u00e9rences et besoins. Qu\u2019il s\u2019agisse d\u2019une collation l\u00e9g\u00e8re ou d\u2019un repas complet, les patients et leurs accompagnants peuvent profiter d\u2019un service de qualit\u00e9 dans un cadre pratique et confortable.<\/p>\n<\/div>                <\/div>\n                                <div class=\"hp-feature-media\">\n                    <img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/bht-clinic-cafe.jpg\" alt=\"Caf\u00e9\" loading=\"lazy\">\n                <\/div>\n                            <\/div>\n\n            \n        \n                        <div class=\"hp-block hp-feature animate-on-scroll\">\n                <div class=\"hp-feature-text\">\n                    <h3 class=\"hp-feature-title\">Bloc op\u00e9ratoire moderne &#8211; fiabilit\u00e9 et technologie<\/h3>                    <div class=\"hp-feature-content\"><p data-start=\"670\" data-end=\"955\">Nos blocs op\u00e9ratoires sont \u00e9quip\u00e9s de technologies m\u00e9dicales avanc\u00e9es et d\u2019\u00e9quipements de pointe n\u00e9cessaires aux proc\u00e9dures d\u2019allongement des membres. Chaque d\u00e9tail y est pens\u00e9 pour garantir un environnement chirurgical s\u00fbr, st\u00e9rile et efficace.<\/p>\n<p data-start=\"957\" data-end=\"1328\">Afin d\u2019offrir le plus haut niveau de soins, les interventions d\u2019allongement des membres sont programm\u00e9es comme premi\u00e8re op\u00e9ration de la journ\u00e9e. Cette approche permet de maintenir des normes d\u2019hygi\u00e8ne maximales et garantit aux patients des conditions op\u00e9ratoires optimales. Gr\u00e2ce \u00e0 l\u2019expertise de notre \u00e9quipe chirurgicale et \u00e0 notre infrastructure avanc\u00e9e, nous visons \u00e0 offrir une exp\u00e9rience de traitement fiable et r\u00e9ussie.<\/p>\n<\/div>                <\/div>\n                                <div class=\"hp-feature-media\">\n                    <img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/modern-operating-room.jpg\" alt=\"Bloc op\u00e9ratoire moderne - fiabilit\u00e9 et technologie\" loading=\"lazy\">\n                <\/div>\n                            <\/div>\n\n            \n        \n                        <div class=\"hp-block hp-certs animate-on-scroll\">\n                <h3 class=\"hp-certs-title\">Certifications et accr\u00e9ditations de notre h\u00f4pital<\/h3>                <p class=\"hp-certs-intro\">Les certifications de notre h\u00f4pital t\u00e9moignent de sa conformit\u00e9 aux normes internationales de qualit\u00e9 et de s\u00e9curit\u00e9. Ces accr\u00e9ditations confirment que toutes les proc\u00e9dures m\u00e9dicales, depuis la pr\u00e9paration pr\u00e9op\u00e9ratoire jusqu\u2019aux soins postop\u00e9ratoires, sont r\u00e9alis\u00e9es dans un cadre s\u00fbr, contr\u00f4l\u00e9 et fiable.\r\n\r\nElles d\u00e9montrent \u00e9galement que la s\u00e9curit\u00e9 des patients, l\u2019hygi\u00e8ne et la qualit\u00e9 des traitements sont maintenues au plus haut niveau tout au long du processus. Gr\u00e2ce \u00e0 ces standards reconnus, les patients peuvent avoir l\u2019assurance de recevoir des soins dans un environnement m\u00e9dical de confiance, g\u00e9r\u00e9 avec professionnalisme.<\/p>                                <div class=\"hp-certs-grid\">\n                                        <div class=\"hp-cert-card\">\n                                                <div class=\"hp-cert-img\"><img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/jci-accreditation.jpg\" alt=\"Accr\u00e9ditation JCI : la r\u00e9f\u00e9rence absolue en mati\u00e8re de qualit\u00e9 et de confiance\" loading=\"lazy\"><\/div>\n                                                <div class=\"hp-cert-body\">\n                            <h4 class=\"hp-cert-title\">Accr\u00e9ditation JCI : la r\u00e9f\u00e9rence absolue en mati\u00e8re de qualit\u00e9 et de confiance<\/h4>                            <p>Le certificat JCI (Joint Commission International) est l\u2019indicateur le plus important du respect des normes internationales en mati\u00e8re de s\u00e9curit\u00e9 des patients et de qualit\u00e9 des services m\u00e9dicaux dans un centre m\u00e9dical. Le JCI, qui figure parmi les accr\u00e9ditations les plus prestigieuses au monde, est consid\u00e9r\u00e9 comme la r\u00e9f\u00e9rence absolue par les \u00e9tablissements qui visent l\u2019excellence dans les services de sant\u00e9 et qui garantissent aux patients les soins les meilleurs et les plus fiables.<\/p>                        <\/div>\n                    <\/div>\n                                        <div class=\"hp-cert-card\">\n                                                <div class=\"hp-cert-img\"><img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/temos.png\" alt=\"Durable et respectueux de l\u2019environnement\" loading=\"lazy\"><\/div>\n                                                <div class=\"hp-cert-body\">\n                            <h4 class=\"hp-cert-title\">Durable et respectueux de l\u2019environnement<\/h4>                            <p>Nous nous engageons \u00e0 fournir des services de sant\u00e9 responsables sur le plan environnemental. Dans cette optique, notre h\u00f4pital partenaire a obtenu la certification Temos LEED Gold, une norme internationale reconnue en mati\u00e8re de durabilit\u00e9 pour les \u00e9tablissements de sant\u00e9.\r\n\r\nCette certification d\u00e9montre que l\u2019h\u00f4pital r\u00e9pond \u00e0 des crit\u00e8res \u00e9lev\u00e9s de performance environnementale, notamment en mati\u00e8re d\u2019efficacit\u00e9 \u00e9nerg\u00e9tique, de pr\u00e9servation de l\u2019eau et de gestion efficace des d\u00e9chets. Elle refl\u00e8te un engagement non seulement envers les soins aux patients, mais aussi envers la protection de l\u2019environnement et la promotion de pratiques durables dans le secteur de la sant\u00e9.<\/p>                        <\/div>\n                    <\/div>\n                                        <div class=\"hp-cert-card\">\n                                                <div class=\"hp-cert-img\"><img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/turquality.jpg\" alt=\"En route pour devenir une marque mondiale avec TURQUALITY\u00ae\" loading=\"lazy\"><\/div>\n                                                <div class=\"hp-cert-body\">\n                            <h4 class=\"hp-cert-title\">En route pour devenir une marque mondiale avec TURQUALITY\u00ae<\/h4>                            <p>Notre h\u00f4pital fait partie du programme TURQUALITY\u00ae, qui soutient le d\u00e9veloppement de la Turquie en tant que marque mondiale dans le secteur de la sant\u00e9. Cette initiative prestigieuse vise \u00e0 renforcer la comp\u00e9titivit\u00e9 internationale des institutions turques et \u00e0 accro\u00eetre la reconnaissance mondiale de la marque \u201cMade in T\u00fcrkiye\u201d.\r\n\r\nEn tant que participant \u00e0 ce programme, l\u2019h\u00f4pital a pass\u00e9 avec succ\u00e8s des \u00e9valuations et des inspections approfondies. Gr\u00e2ce au soutien apport\u00e9 par TURQUALITY\u00ae, il continue d\u2019am\u00e9liorer ses standards de service, de renforcer sa pr\u00e9sence internationale et d\u2019accro\u00eetre sa valeur de marque globale.<\/p>                        <\/div>\n                    <\/div>\n                                        <div class=\"hp-cert-card\">\n                                                <div class=\"hp-cert-img\"><img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/efqm.png\" alt=\"EFQM - am\u00e9lioration continue avec le mod\u00e8le d\u2019excellence\" loading=\"lazy\"><\/div>\n                                                <div class=\"hp-cert-body\">\n                            <h4 class=\"hp-cert-title\">EFQM &#8211; am\u00e9lioration continue avec le mod\u00e8le d\u2019excellence<\/h4>                            <p>Notre h\u00f4pital a franchi une \u00e9tape importante vers l\u2019am\u00e9lioration continue en adoptant le mod\u00e8le d\u2019excellence d\u00e9velopp\u00e9 par la Fondation europ\u00e9enne pour le management de la qualit\u00e9 (EFQM). Ce mod\u00e8le fournit un cadre complet qui aide les organisations \u00e0 am\u00e9liorer leurs performances, optimiser leurs processus et atteindre un succ\u00e8s durable.\r\n\r\nEn mettant en \u0153uvre les standards EFQM, notre h\u00f4pital d\u00e9montre un engagement fort envers la satisfaction des patients, l\u2019implication du personnel et l\u2019excellence op\u00e9rationnelle. Cette reconnaissance refl\u00e8te une culture d\u2019am\u00e9lioration continue et une volont\u00e9 de fournir des services de sant\u00e9 de haute qualit\u00e9 \u00e0 tous les niveaux.<\/p>                        <\/div>\n                    <\/div>\n                                        <div class=\"hp-cert-card\">\n                                                <div class=\"hp-cert-img\"><img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/leed-gold.png\" alt=\"LEED GOLD - une r\u00e9ussite d\u2019excellence dans les standards de construction durable\" loading=\"lazy\"><\/div>\n                                                <div class=\"hp-cert-body\">\n                            <h4 class=\"hp-cert-title\">LEED GOLD &#8211; une r\u00e9ussite d\u2019excellence dans les standards de construction durable<\/h4>                            <p>Notre h\u00f4pital se distingue par son engagement fort en faveur de la responsabilit\u00e9 environnementale et de la durabilit\u00e9. Il a obtenu la certification LEED Gold en atteignant des standards \u00e9lev\u00e9s dans des domaines tels que l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique, la pr\u00e9servation de l\u2019eau et la gestion efficace des d\u00e9chets.\r\n\r\nCette prestigieuse certification refl\u00e8te l\u2019engagement de l\u2019h\u00f4pital non seulement \u00e0 fournir des services m\u00e9dicaux de haute qualit\u00e9, mais aussi \u00e0 prot\u00e9ger l\u2019environnement. Elle illustre une approche \u00e9quilibr\u00e9e dans laquelle l\u2019excellence en sant\u00e9 et les pratiques durables avancent main dans la main.<\/p>                        <\/div>\n                    <\/div>\n                                    <\/div>\n                            <\/div>\n\n            \n        \n                        <div class=\"hp-block hp-prayer animate-on-scroll\">\n                <p class=\"hp-prayer-intro\">De plus, notre h\u00f4pital dispose de salles de pri\u00e8re pour les patients de diff\u00e9rentes confessions religieuses.\r\n\r\n<\/p>                                <div class=\"hp-prayer-grid\">\n                                        <div class=\"hp-prayer-card\">\n                                                <img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/masjid.jpg\" alt=\"Mosqu\u00e9e\" loading=\"lazy\">\n                                                <span class=\"hp-prayer-name\">Mosqu\u00e9e<\/span>                    <\/div>\n                                        <div class=\"hp-prayer-card\">\n                                                <img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/chapel.jpg\" alt=\"Chapelle\" loading=\"lazy\">\n                                                <span class=\"hp-prayer-name\">Chapelle<\/span>                    <\/div>\n                                        <div class=\"hp-prayer-card\">\n                                                <img decoding=\"async\" src=\"https:\/\/dryunusoc.com\/wp-content\/uploads\/2026\/04\/synagogue.jpg\" alt=\"Synagogue\" loading=\"lazy\">\n                                                <span class=\"hp-prayer-name\">Synagogue<\/span>                    <\/div>\n                                    <\/div>\n                            <\/div>\n\n            \n        \n    <\/div>\n<\/section>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-text-color has-link-color wp-elements-1\" style=\"color:#0a3a7d;font-size:29px\">FAQ<\/h2>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Quelles techniques d\u2019allongement des membres sont pratiqu\u00e9es dans notre h\u00f4pital ?<\/summary>\n<p class=\"wp-block-paragraph\">Dans notre h\u00f4pital, des techniques modernes d\u2019allongement des membres telles que Precice, Fitbone et LON sont pratiqu\u00e9es. Ces m\u00e9thodes repr\u00e9sentent les derni\u00e8res avanc\u00e9es en chirurgie orthop\u00e9dique et sont s\u00e9lectionn\u00e9es en fonction de l\u2019\u00e9tat du patient, de ses attentes et de ses objectifs de traitement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chaque technique pr\u00e9sente des avantages diff\u00e9rents en mati\u00e8re de confort, de mobilit\u00e9 et de r\u00e9cup\u00e9ration. Les syst\u00e8mes enti\u00e8rement internes comme Precice et Fitbone offrent davantage de confort et de meilleurs r\u00e9sultats esth\u00e9tiques, tandis que la m\u00e9thode LON apporte un soutien m\u00e9canique solide et une reprise assist\u00e9e de la mobilit\u00e9 plus pr\u00e9coce. La m\u00e9thode la plus adapt\u00e9e est d\u00e9termin\u00e9e apr\u00e8s une \u00e9valuation m\u00e9dicale d\u00e9taill\u00e9e.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Combien de jours d\u2019hospitalisation sont n\u00e9cessaires dans notre h\u00f4pital ?<\/summary>\n<p class=\"wp-block-paragraph\">Apr\u00e8s une chirurgie d\u2019allongement des membres, les patients doivent g\u00e9n\u00e9ralement rester \u00e0 l\u2019h\u00f4pital pendant environ 5 jours. Pendant cette p\u00e9riode, l\u2019\u00e9quipe m\u00e9dicale surveille attentivement l\u2019\u00e9tat du patient, g\u00e8re la douleur et veille \u00e0 ce que la phase initiale de r\u00e9cup\u00e9ration se d\u00e9roule en toute s\u00e9curit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En outre, les soins postop\u00e9ratoires tels que la prise en charge des plaies, les contr\u00f4les m\u00e9dicaux et la physioth\u00e9rapie pr\u00e9coce sont mis en place. Les patients sont pr\u00e9par\u00e9s \u00e0 l\u2019\u00e9tape suivante de leur r\u00e9cup\u00e9ration avant leur sortie, assurant ainsi une transition fluide vers le processus de r\u00e9\u00e9ducation.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Quelles accr\u00e9ditations internationales notre h\u00f4pital poss\u00e8de-t-il ?<\/summary>\n<p class=\"wp-block-paragraph\">Notre h\u00f4pital dispose d\u2019accr\u00e9ditations internationalement reconnues telles que JCI, TEMOS et LEED GOLD. Ces certifications d\u00e9montrent que nous r\u00e9pondons aux normes mondiales en mati\u00e8re de s\u00e9curit\u00e9 des patients, de qualit\u00e9 des soins et d\u2019hygi\u00e8ne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces accr\u00e9ditations garantissent que toutes les proc\u00e9dures m\u00e9dicales sont r\u00e9alis\u00e9es dans un environnement contr\u00f4l\u00e9 et fiable. De la pr\u00e9paration pr\u00e9op\u00e9ratoire aux soins postop\u00e9ratoires, chaque \u00e9tape suit des protocoles internationaux stricts.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Quelles technologies m\u00e9dicales sont utilis\u00e9es dans notre h\u00f4pital ?<\/summary>\n<p class=\"wp-block-paragraph\">L\u2019h\u00f4pital est \u00e9quip\u00e9 de technologies m\u00e9dicales avanc\u00e9es telles que l\u2019IRM corps entier, le PET-CT, l\u2019angiographie num\u00e9rique et des syst\u00e8mes d\u2019imagerie modernes. Ces outils permettent un diagnostic pr\u00e9cis, une planification d\u00e9taill\u00e9e et une ex\u00e9cution s\u00fbre des proc\u00e9dures d\u2019allongement des membres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce au soutien de ces technologies, les interventions chirurgicales sont r\u00e9alis\u00e9es avec un niveau sup\u00e9rieur de pr\u00e9cision et de fiabilit\u00e9. Cela garantit de meilleurs r\u00e9sultats th\u00e9rapeutiques et renforce la s\u00e9curit\u00e9 des patients tout au long du processus.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Quelles sont les conditions des chambres des patients dans notre h\u00f4pital ?<\/summary>\n<p class=\"wp-block-paragraph\">Les chambres des patients sont con\u00e7ues pour offrir un confort maximal pendant la p\u00e9riode de r\u00e9cup\u00e9ration. Elles sont spacieuses, modernes et \u00e9quip\u00e9es de lits hospitaliers r\u00e9glables ainsi que du mat\u00e9riel m\u00e9dical essentiel pour r\u00e9pondre aux besoins des patients.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En outre, les chambres sont entretenues selon des normes d\u2019hygi\u00e8ne \u00e9lev\u00e9es et offrent un environnement calme qui soutient \u00e0 la fois la r\u00e9cup\u00e9ration physique et mentale. Cela permet aux patients de se sentir en s\u00e9curit\u00e9 et \u00e0 l\u2019aise pendant toute la dur\u00e9e de leur s\u00e9jour.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Quels \u00e9quipements sont disponibles pour les patients \u00e0 mobilit\u00e9 r\u00e9duite dans notre h\u00f4pital ?<\/summary>\n<p class=\"wp-block-paragraph\">L\u2019h\u00f4pital propose des installations sp\u00e9cialement con\u00e7ues pour les patients \u00e0 mobilit\u00e9 r\u00e9duite, notamment des salles de bain accessibles, des \u00e9quipements de soutien et des am\u00e9nagements de chambres s\u00e9curis\u00e9s. Ces \u00e9l\u00e9ments permettent aux patients de conserver leur autonomie pendant la r\u00e9cup\u00e9ration.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tous les espaces sont con\u00e7us selon des normes d\u2019accessibilit\u00e9, garantissant des d\u00e9placements s\u00fbrs dans tout l\u2019h\u00f4pital. Cela r\u00e9duit les risques et am\u00e9liore le confort global pendant le processus de traitement.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Notre h\u00f4pital accueille-t-il des patients internationaux ?<\/summary>\n<p class=\"wp-block-paragraph\">Oui, l\u2019h\u00f4pital accueille des patients du monde entier dans le cadre du tourisme m\u00e9dical international. Les patients b\u00e9n\u00e9ficient d\u2019un accompagnement tout au long du processus, depuis leur arriv\u00e9e jusqu\u2019au traitement et au suivi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des services sp\u00e9cifiques tels que la communication multilingue, les transferts a\u00e9roport, l\u2019h\u00e9bergement et la coordination sont propos\u00e9s afin de garantir une exp\u00e9rience fluide et confortable.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Quels services sont propos\u00e9s aux patients internationaux dans notre h\u00f4pital ?<\/summary>\n<p class=\"wp-block-paragraph\">Les patients internationaux b\u00e9n\u00e9ficient de services complets comprenant un accompagnement linguistique, les transferts a\u00e9roport, l\u2019organisation de l\u2019h\u00e9bergement et une assistance personnalis\u00e9e. Ces services sont con\u00e7us pour rendre le parcours de traitement plus simple et plus confortable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des coordinateurs d\u00e9di\u00e9s accompagnent les patients internationaux \u00e0 chaque \u00e9tape, garantissant une communication claire et une organisation fluide tout au long du parcours de soins.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Notre h\u00f4pital est-il \u00e9quip\u00e9 de blocs op\u00e9ratoires modernes ?<\/summary>\n<p class=\"wp-block-paragraph\">Oui, l\u2019h\u00f4pital dispose de blocs op\u00e9ratoires modernes \u00e9quip\u00e9s de technologies m\u00e9dicales avanc\u00e9es. Ces blocs sont con\u00e7us pour garantir un environnement chirurgical st\u00e9rile, s\u00fbr et efficace.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les interventions sont r\u00e9alis\u00e9es dans le respect de normes d\u2019hygi\u00e8ne strictes et par des \u00e9quipes chirurgicales exp\u00e9riment\u00e9es, garantissant des taux de r\u00e9ussite \u00e9lev\u00e9s et la s\u00e9curit\u00e9 des patients.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Comment puis-je contacter notre h\u00f4pital pour prendre rendez-vous ?<\/summary>\n<p class=\"wp-block-paragraph\">Vous pouvez <a href=\"https:\/\/dryunusoc.com\/fr\/contact\/\">nous contacter<\/a> pour prendre rendez-vous via le formulaire ou les coordonn\u00e9es disponibles sur notre page de contact.<\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FAQ<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"class_list":["post-2132","page","type-page","status-publish","hentry"],"acf":[],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/dryunusoc.com\/fr\/wp-json\/wp\/v2\/pages\/2132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dryunusoc.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dryunusoc.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dryunusoc.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dryunusoc.com\/fr\/wp-json\/wp\/v2\/comments?post=2132"}],"version-history":[{"count":8,"href":"https:\/\/dryunusoc.com\/fr\/wp-json\/wp\/v2\/pages\/2132\/revisions"}],"predecessor-version":[{"id":3574,"href":"https:\/\/dryunusoc.com\/fr\/wp-json\/wp\/v2\/pages\/2132\/revisions\/3574"}],"wp:attachment":[{"href":"https:\/\/dryunusoc.com\/fr\/wp-json\/wp\/v2\/media?parent=2132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}